{"id":6312,"date":"2011-10-10T11:36:53","date_gmt":"2011-10-10T10:36:53","guid":{"rendered":"http:\/\/azahar-sevilla.com\/sevilletapas\/?p=6312"},"modified":"2026-05-10T16:58:33","modified_gmt":"2026-05-10T15:58:33","slug":"cafeteria-donald","status":"publish","type":"post","link":"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/","title":{"rendered":"Cafeter\u00eda Donald"},"content":{"rendered":"<h3>Updated May 2026<\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37143\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-25-14\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-14.jpg?fit=640%2C490&amp;ssl=1\" data-orig-size=\"640,490\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1755952334&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.0012936610608021&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 25 (14)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-14.jpg?fit=640%2C490&amp;ssl=1\" class=\"aligncenter size-full wp-image-37143\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-14.jpg?resize=640%2C490&#038;ssl=1\" alt=\"\" width=\"640\" height=\"490\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-14.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-14.jpg?resize=300%2C230&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-14.jpg?resize=618%2C473&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-14.jpg?resize=444%2C340&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">Cafeter\u00eda Donald has been going strong for 52 years and is a neighbourhood taurino-themed tapas bar and restaurant that serves up award-winning <a href=\"http:\/\/www.jamoneseiriz.com\/web\/jamon_iberico_regalo_salud.php\" target=\"_blank\" rel=\"noopener noreferrer\">Eiriz jamones<\/a> (also award-winning ensaladilla) along with fresh fish and seafood brought in daily from Huelva. It&#8217;s also my local, just a few minutes from my house. My favourite spot is at the bar, but you can also choose between the side walk terrace or upstairs dining room. The homespun tapas &#8211; only available at the bar &#8211; are delish, the service friendly and professional, and the ambiance lively and fun.<\/p>\n<p style=\"text-align: justify;\">First opened in 1973, the Donald is now owned and run by former waiter Mariano Garc\u00eda, who took over after the original owner retired in 1987, and boasts three generations of loyal clientele including well-known bullfighters and other celebrities. And the name? When I asked Mariano &#8220;why Cafeter\u00eda Donald?&#8221; and was told that it had actually been called Bar Donald Duck by the original owner until he was threatened with legal action by Disney. Which not only answered the question, but also explained his Donald Duck tie. This past year he has been joined by his daughter Conchi, who is keen to carry on the family tradition.<\/p>\n<p style=\"text-align: justify;\">Have the ensaladilla (of course) and some of their excellent fritos. The solomillo al whisky is great too. They also do a whole braised lamb shoulder along with their fresh fish options. Classic tapas, unchanged since the 1970s, a decent wine list&#8230; it&#8217;s pure Sevilla here.<\/p>\n<p>You can read more about their story here&#8230; <a href=\"https:\/\/shawnhennessey.substack.com\/p\/the-donald\" target=\"_blank\" rel=\"noopener\"><strong>The Donald (Bitesize Sevilla)<\/strong><\/a><\/p>\n<blockquote><p><a href=\"https:\/\/www.google.com\/maps\/place\/Bar+Donald\/@37.3906356,-5.9993918,15z\/data=!4m5!3m4!1s0x0:0xb7a6f5e3cfa7c7a0!8m2!3d37.3906342!4d-5.999391\" target=\"_blank\" rel=\"noopener\">Canalejas 3<\/a><br \/>\ntel. 954227252 \/ 954218195<br \/>\nOpen 13.00 &#8211; midnight<br \/>\nAll Day Kitchen<br \/>\nClosed Tuesdays<br \/>\n<span style=\"color: #ff6600;\"> <strong>\u20ac \u20ac \u20ac<\/strong><\/span><\/p><\/blockquote>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-780\" title=\"orange\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/wp-content\/uploads\/2009\/06\/orange.gif?resize=17%2C28\" alt=\"orange\" width=\"17\" height=\"28\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-780\" title=\"orange\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/wp-content\/uploads\/2009\/06\/orange.gif?resize=17%2C28\" alt=\"orange\" width=\"17\" height=\"28\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-780\" title=\"orange\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/wp-content\/uploads\/2009\/06\/orange.gif?resize=17%2C28\" alt=\"orange\" width=\"17\" height=\"28\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-780\" title=\"orange\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/wp-content\/uploads\/2009\/06\/orange.gif?resize=17%2C28\" alt=\"orange\" width=\"17\" height=\"28\" \/><br \/>\nFood 9 | Wine 7 | Service 8 | Ambiance 8<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"36107\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-25-9\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-9.jpg?fit=640%2C476&amp;ssl=1\" data-orig-size=\"640,476\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1740228000&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 25 (9)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-9.jpg?fit=640%2C476&amp;ssl=1\" class=\"aligncenter size-full wp-image-36107\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-9.jpg?resize=640%2C476&#038;ssl=1\" alt=\"\" width=\"640\" height=\"476\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-9.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-9.jpg?resize=300%2C223&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-9.jpg?resize=618%2C460&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-9.jpg?resize=138%2C104&amp;ssl=1 138w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-9.jpg?resize=444%2C330&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37978\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26.jpg?fit=580%2C640&amp;ssl=1\" data-orig-size=\"580,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769087246&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26.jpg?fit=580%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-37978\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26.jpg?resize=580%2C640&#038;ssl=1\" alt=\"\" width=\"580\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26.jpg?w=580&amp;ssl=1 580w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26.jpg?resize=272%2C300&amp;ssl=1 272w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26.jpg?resize=402%2C444&amp;ssl=1 402w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19379\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-carta-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-carta-1.jpg?fit=374%2C500&amp;ssl=1\" data-orig-size=\"374,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 4&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1318084951&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.85&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.0333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald carta\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-carta-1.jpg?fit=374%2C500&amp;ssl=1\" class=\"aligncenter wp-image-19379\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-carta-1.jpg?resize=448%2C599&#038;ssl=1\" alt=\"\" width=\"448\" height=\"599\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-carta-1.jpg?w=374&amp;ssl=1 374w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-carta-1.jpg?resize=224%2C300&amp;ssl=1 224w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-carta-1.jpg?resize=332%2C444&amp;ssl=1 332w\" sizes=\"auto, (max-width: 448px) 100vw, 448px\" \/>the menu<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37973\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-3\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-3.jpg?fit=640%2C601&amp;ssl=1\" data-orig-size=\"640,601\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769088912&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (3)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-3.jpg?fit=640%2C601&amp;ssl=1\" class=\"alignnone size-full wp-image-37973 aligncenter\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-3.jpg?resize=640%2C601&#038;ssl=1\" alt=\"\" width=\"640\" height=\"601\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-3.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-3.jpg?resize=300%2C282&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-3.jpg?resize=618%2C580&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-3.jpg?resize=444%2C417&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>queso zamarano, ca\u00f1a de lomo Ib\u00e9rico, jam\u00f3n Ib\u00e9rico de Bellota<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37974\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-4\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-4.jpg?fit=596%2C640&amp;ssl=1\" data-orig-size=\"596,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769089097&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (4)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-4.jpg?fit=596%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-37974\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-4.jpg?resize=596%2C640&#038;ssl=1\" alt=\"\" width=\"596\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-4.jpg?w=596&amp;ssl=1 596w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-4.jpg?resize=279%2C300&amp;ssl=1 279w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-4.jpg?resize=413%2C444&amp;ssl=1 413w\" sizes=\"auto, (max-width: 596px) 100vw, 596px\" \/><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"31326\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-ensaladilla\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-ensaladilla.jpg?fit=640%2C632&amp;ssl=1\" data-orig-size=\"640,632\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 12 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1686580169&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald ensaladilla\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-ensaladilla.jpg?fit=640%2C632&amp;ssl=1\" class=\"aligncenter size-full wp-image-31326\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-ensaladilla.jpg?resize=640%2C632&#038;ssl=1\" alt=\"\" width=\"640\" height=\"632\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-ensaladilla.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-ensaladilla.jpg?resize=300%2C296&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-ensaladilla.jpg?resize=618%2C610&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-ensaladilla.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-ensaladilla.jpg?resize=444%2C438&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>award-winning ensaladilla<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"38558\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-10\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-10.jpg?fit=640%2C632&amp;ssl=1\" data-orig-size=\"640,632\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1770899712&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0067567567567568&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (10)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-10.jpg?fit=640%2C632&amp;ssl=1\" class=\"aligncenter size-full wp-image-38558\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-10.jpg?resize=640%2C632&#038;ssl=1\" alt=\"\" width=\"640\" height=\"632\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-10.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-10.jpg?resize=300%2C296&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-10.jpg?resize=618%2C610&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-10.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-10.jpg?resize=444%2C438&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>boquerones al vinagre<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"34744\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-24-1\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-1.jpg?fit=640%2C640&amp;ssl=1\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1723642578&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 24 (1)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-1.jpg?fit=640%2C640&amp;ssl=1\" class=\"alignnone size-full wp-image-34744\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-1.jpg?resize=640%2C640&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-1.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-1.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-1.jpg?resize=618%2C618&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-1.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-1.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><br \/>\nsalpic\u00f3n de mariscos (seafood salad)<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"38559\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-11\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-11.jpg?fit=640%2C635&amp;ssl=1\" data-orig-size=\"640,635\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1770899766&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (11)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-11.jpg?fit=640%2C635&amp;ssl=1\" class=\"aligncenter size-full wp-image-38559\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-11.jpg?resize=640%2C635&#038;ssl=1\" alt=\"\" width=\"640\" height=\"635\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-11.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-11.jpg?resize=300%2C298&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-11.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-11.jpg?resize=618%2C613&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-11.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-11.jpg?resize=444%2C441&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>fresh mussels<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"38574\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-15\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-15.jpg?fit=640%2C629&amp;ssl=1\" data-orig-size=\"640,629\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1773937166&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0082644628099174&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (15)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-15.jpg?fit=640%2C629&amp;ssl=1\" class=\"aligncenter size-full wp-image-38574\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-15.jpg?resize=640%2C629&#038;ssl=1\" alt=\"\" width=\"640\" height=\"629\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-15.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-15.jpg?resize=300%2C295&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-15.jpg?resize=618%2C607&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-15.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-15.jpg?resize=444%2C436&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>tuna stuffed eggs<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"38575\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-16\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-16.jpg?fit=640%2C640&amp;ssl=1\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1773937204&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (16)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-16.jpg?fit=640%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-38575\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-16.jpg?resize=640%2C640&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-16.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-16.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-16.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-16.jpg?resize=618%2C618&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-16.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-16.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"24478\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-13\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-13.jpg?fit=500%2C494&amp;ssl=1\" data-orig-size=\"500,494\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1557508749&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald (13)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-13.jpg?fit=500%2C494&amp;ssl=1\" class=\"aligncenter wp-image-24478\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-13.jpg?resize=596%2C589&#038;ssl=1\" alt=\"\" width=\"596\" height=\"589\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-13.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-13.jpg?resize=300%2C296&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-13.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-13.jpg?resize=444%2C439&amp;ssl=1 444w\" sizes=\"auto, (max-width: 596px) 100vw, 596px\" \/>gambas al ajillo<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6299\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/?attachment_id=6299#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-swordfish.jpg?fit=369%2C480&amp;ssl=1\" data-orig-size=\"369,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 4&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1318084871&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.85&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;smoothgallery_link&quot;:&quot;&quot;}\" data-image-title=\"donald swordfish\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-swordfish.jpg?fit=369%2C480&amp;ssl=1\" class=\"aligncenter wp-image-6299\" title=\"donald swordfish\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-swordfish.jpg?resize=552%2C719&#038;ssl=1\" alt=\"\" width=\"552\" height=\"719\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-swordfish.jpg?w=369&amp;ssl=1 369w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-swordfish.jpg?resize=230%2C300&amp;ssl=1 230w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-swordfish.jpg?resize=115%2C150&amp;ssl=1 115w\" sizes=\"auto, (max-width: 552px) 100vw, 552px\" \/>grilled swordfish with garic and parsley sauce<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"23437\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-6\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-6.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1544470461&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald (6)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-6.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-23437\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-6.jpg?resize=601%2C601&#038;ssl=1\" alt=\"\" width=\"601\" height=\"601\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-6.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-6.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-6.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-6.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-6.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/>judiones (large butter beans) with prawns<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19396\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-pollow\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pollow.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 6s&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1501706578&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.15&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald pollow\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pollow.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-19396\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pollow.jpg?resize=600%2C600&#038;ssl=1\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pollow.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pollow.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pollow.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pollow.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pollow.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>grilled chicken breast with alioli<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21943\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/img_4563\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4563.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1533391143&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.0416666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_4563\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4563.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-21943\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4563.jpg?resize=603%2C603&#038;ssl=1\" alt=\"\" width=\"603\" height=\"603\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4563.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4563.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4563.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4563.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4563.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 603px) 100vw, 603px\" \/>grilled pork loin with garlicky tomato sauce<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21663\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-pinchito-pork\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-pork.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1531402960&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald pinchito pork\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-pork.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-21663\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-pork.jpg?resize=598%2C598&#038;ssl=1\" alt=\"\" width=\"598\" height=\"598\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-pork.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-pork.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-pork.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-pork.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-pork.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/>pork pinchito moruno<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21664\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-pinchito-chicken\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-chicken.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1531402992&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald pinchito chicken\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-chicken.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-21664\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-chicken.jpg?resize=597%2C597&#038;ssl=1\" alt=\"\" width=\"597\" height=\"597\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-chicken.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-chicken.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-chicken.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-chicken.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-pinchito-chicken.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/>chicken pinchito<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"22699\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/img_0476\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0476.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1541100687&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_0476\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0476.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-22699\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0476.jpg?resize=603%2C603&#038;ssl=1\" alt=\"\" width=\"603\" height=\"603\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0476.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0476.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0476.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0476.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0476.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 603px) 100vw, 603px\" \/>breaded chicken breast with bechamel<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"34745\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-24-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-2.jpg?fit=640%2C640&amp;ssl=1\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1723643877&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 24 (2)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-2.jpg?fit=640%2C640&amp;ssl=1\" class=\"alignnone size-full wp-image-34745 aligncenter\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-2.jpg?resize=640%2C640&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-2.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-2.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-2.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-2.jpg?resize=618%2C618&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-2.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-2.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>lubina (sea bass) with bilbaina sauce<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"24720\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-beef-sausages\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-beef-sausages.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1565732722&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.0588235294118&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald beef sausages\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-beef-sausages.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-24720\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-beef-sausages.jpg?resize=607%2C607&#038;ssl=1\" alt=\"\" width=\"607\" height=\"607\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-beef-sausages.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-beef-sausages.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-beef-sausages.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-beef-sausages.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-beef-sausages.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 607px) 100vw, 607px\" \/>locally produced beef sausages<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"22700\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/img_0453\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0453.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1541099718&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_0453\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0453.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-22700\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0453.jpg?resize=599%2C599&#038;ssl=1\" alt=\"\" width=\"599\" height=\"599\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0453.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0453.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0453.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0453.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_0453.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 599px) 100vw, 599px\" \/>ham, salchicha and cheese flamenqu\u00edn<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21945\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/img_4605\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4605.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1533392018&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.0416666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_4605\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4605.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-21945\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4605.jpg?resize=600%2C600&#038;ssl=1\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4605.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4605.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4605.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4605.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4605.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>fried aubergine filled with beef, topped with onion sauce<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19620\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-espinacas\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-espinacas.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 6s&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1504708214&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.15&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald espinacas\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-espinacas.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-19620\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-espinacas.jpg?resize=600%2C600&#038;ssl=1\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-espinacas.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-espinacas.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-espinacas.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-espinacas.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-espinacas.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>spinach with garbanzos<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"34931\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-24-4\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-4.jpg?fit=640%2C640&amp;ssl=1\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1728737429&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 24 (4)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-4.jpg?fit=640%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-34931\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-4.jpg?resize=640%2C640&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-4.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-4.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-4.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-4.jpg?resize=618%2C618&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-4.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-4.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>pav\u00eda de bacalao<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"34932\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-24-5\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-5.jpg?fit=640%2C640&amp;ssl=1\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1728737499&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 24 (5)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-5.jpg?fit=640%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-34932\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-5.jpg?resize=640%2C640&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-5.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-5.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-5.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-5.jpg?resize=618%2C618&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-5.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-5.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"34933\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-24-6\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-6.jpg?fit=640%2C640&amp;ssl=1\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1728738932&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 24 (6)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-6.jpg?fit=640%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-34933\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-6.jpg?resize=640%2C640&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-6.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-6.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-6.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-6.jpg?resize=618%2C618&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-6.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-6.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>battered prawns<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"24475\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-10\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-10.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1557505278&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald (10)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-10.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-24475\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-10.jpg?resize=601%2C601&#038;ssl=1\" alt=\"\" width=\"601\" height=\"601\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-10.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-10.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-10.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-10.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-10.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/>percebes (gooseneck barnacles)<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"24476\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-11\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-11.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1557505344&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald (11)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-11.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-24476\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-11.jpg?resize=604%2C604&#038;ssl=1\" alt=\"\" width=\"604\" height=\"604\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-11.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-11.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-11.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-11.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-11.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"38560\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-12\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-12.jpg?fit=640%2C606&amp;ssl=1\" data-orig-size=\"640,606\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1770901526&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (12)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-12.jpg?fit=640%2C606&amp;ssl=1\" class=\"aligncenter size-full wp-image-38560\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-12.jpg?resize=640%2C606&#038;ssl=1\" alt=\"\" width=\"640\" height=\"606\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-12.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-12.jpg?resize=300%2C284&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-12.jpg?resize=618%2C585&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-12.jpg?resize=444%2C420&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>fried salmonetes<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"38561\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-13\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-13.jpg?fit=567%2C640&amp;ssl=1\" data-orig-size=\"567,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1770902402&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0070422535211268&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (13)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-13.jpg?fit=567%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-38561\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-13.jpg?resize=567%2C640&#038;ssl=1\" alt=\"\" width=\"567\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-13.jpg?w=567&amp;ssl=1 567w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-13.jpg?resize=266%2C300&amp;ssl=1 266w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-13.jpg?resize=393%2C444&amp;ssl=1 393w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37972\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-2.jpg?fit=640%2C640&amp;ssl=1\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769088804&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (2)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-2.jpg?fit=640%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-37972\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-2.jpg?resize=640%2C640&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-2.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-2.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-2.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-2.jpg?resize=618%2C618&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-2.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-2.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>boquerones fritos<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37975\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-5\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-5.jpg?fit=559%2C640&amp;ssl=1\" data-orig-size=\"559,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769089234&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0082644628099174&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (5)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-5.jpg?fit=559%2C640&amp;ssl=1\" class=\"alignnone size-full wp-image-37975\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-5.jpg?resize=559%2C640&#038;ssl=1\" alt=\"\" width=\"559\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-5.jpg?w=559&amp;ssl=1 559w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-5.jpg?resize=262%2C300&amp;ssl=1 262w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-5.jpg?resize=388%2C444&amp;ssl=1 388w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><br \/>\nwhole calamar frito<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37976\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-6\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-6.jpg?fit=640%2C631&amp;ssl=1\" data-orig-size=\"640,631\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769089247&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (6)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-6.jpg?fit=640%2C631&amp;ssl=1\" class=\"alignnone size-full wp-image-37976 aligncenter\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-6.jpg?resize=640%2C631&#038;ssl=1\" alt=\"\" width=\"640\" height=\"631\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-6.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-6.jpg?resize=300%2C296&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-6.jpg?resize=618%2C609&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-6.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-6.jpg?resize=444%2C438&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"20628\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-galeras-al-ajillo\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-galeras-al-ajillo.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1517257276&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald galeras al ajillo\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-galeras-al-ajillo.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-20628\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-galeras-al-ajillo.jpg?resize=599%2C599&#038;ssl=1\" alt=\"\" width=\"599\" height=\"599\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-galeras-al-ajillo.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-galeras-al-ajillo.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-galeras-al-ajillo.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-galeras-al-ajillo.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-galeras-al-ajillo.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 599px) 100vw, 599px\" \/>galeras al ajillo<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"38576\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-17\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-17.jpg?fit=640%2C640&amp;ssl=1\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1773937176&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (17)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-17.jpg?fit=640%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-38576\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-17.jpg?resize=640%2C640&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-17.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-17.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-17.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-17.jpg?resize=618%2C618&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-17.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-17.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>pork kidneys in sherry sauce<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19619\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-atun-tomate\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-atun-tomate.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 6s&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1504708194&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.15&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald atun tomate\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-atun-tomate.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-19619\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-atun-tomate.jpg?resize=598%2C598&#038;ssl=1\" alt=\"\" width=\"598\" height=\"598\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-atun-tomate.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-atun-tomate.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-atun-tomate.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-atun-tomate.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-atun-tomate.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/>stewed tuna in tomato sauce<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"36110\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-25-12\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-12.jpg?fit=640%2C640&amp;ssl=1\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1740229772&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 25 (12)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-12.jpg?fit=640%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-36110\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-12.jpg?resize=640%2C640&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-12.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-12.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-12.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-12.jpg?resize=618%2C618&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-12.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-12.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>solomillo al whisky<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"36111\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-25-13\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-13.jpg?fit=640%2C640&amp;ssl=1\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1740229780&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 25 (13)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-13.jpg?fit=640%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-36111\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-13.jpg?resize=640%2C640&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-13.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-13.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-13.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-13.jpg?resize=618%2C618&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-13.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-13.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19395\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-meatballs\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-meatballs.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 6s&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1501705385&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.15&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald meatballs\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-meatballs.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-19395\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-meatballs.jpg?resize=606%2C606&#038;ssl=1\" alt=\"\" width=\"606\" height=\"606\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-meatballs.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-meatballs.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-meatballs.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-meatballs.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-meatballs.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 606px) 100vw, 606px\" \/>beef meatballs<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"34930\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-24-3\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-3.jpg?fit=633%2C640&amp;ssl=1\" data-orig-size=\"633,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1728752553&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 24 (3)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-3.jpg?fit=633%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-34930\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-3.jpg?resize=633%2C640&#038;ssl=1\" alt=\"\" width=\"633\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-3.jpg?w=633&amp;ssl=1 633w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-3.jpg?resize=297%2C300&amp;ssl=1 297w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-3.jpg?resize=618%2C625&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-3.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-24-3.jpg?resize=439%2C444&amp;ssl=1 439w\" sizes=\"auto, (max-width: 633px) 100vw, 633px\" \/>roasted pork loin al jerez<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21944\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/img_4589\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4589.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1533392648&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_4589\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4589.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-21944\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4589.jpg?resize=601%2C601&#038;ssl=1\" alt=\"\" width=\"601\" height=\"601\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4589.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4589.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4589.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4589.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/IMG_4589.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/>whole leg of lamb<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19623\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-entrecote\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-entrecote.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 6s&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1504709599&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.15&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald entrecote\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-entrecote.jpg?fit=500%2C500&amp;ssl=1\" class=\"aligncenter wp-image-19623\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-entrecote.jpg?resize=601%2C601&#038;ssl=1\" alt=\"\" width=\"601\" height=\"601\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-entrecote.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-entrecote.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-entrecote.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-entrecote.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-entrecote.jpg?resize=444%2C444&amp;ssl=1 444w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/>grilled beef entrecote<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37977\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-7\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-7.jpg?fit=640%2C630&amp;ssl=1\" data-orig-size=\"640,630\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1769092315&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (7)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-7.jpg?fit=640%2C630&amp;ssl=1\" class=\"aligncenter size-full wp-image-37977\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-7.jpg?resize=640%2C630&#038;ssl=1\" alt=\"\" width=\"640\" height=\"630\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-7.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-7.jpg?resize=300%2C295&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-7.jpg?resize=618%2C608&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-7.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-7.jpg?resize=444%2C437&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>cheese aged in manteca<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6305\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/?attachment_id=6305#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-fish-display.jpg?fit=480%2C356&amp;ssl=1\" data-orig-size=\"480,356\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.7&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;COOLPIX S6000&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;2145916740&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;smoothgallery_link&quot;:&quot;&quot;}\" data-image-title=\"donald fish display\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-fish-display.jpg?fit=480%2C356&amp;ssl=1\" class=\"aligncenter wp-image-6305\" title=\"donald fish display\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-fish-display.jpg?resize=607%2C450&#038;ssl=1\" alt=\"\" width=\"607\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-fish-display.jpg?w=480&amp;ssl=1 480w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-fish-display.jpg?resize=300%2C222&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-fish-display.jpg?resize=150%2C111&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-fish-display.jpg?resize=400%2C296&amp;ssl=1 400w\" sizes=\"auto, (max-width: 607px) 100vw, 607px\" \/>fresh fish display<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6304\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/?attachment_id=6304#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-jamones.jpg?fit=480%2C360&amp;ssl=1\" data-orig-size=\"480,360\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.7&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;COOLPIX S6000&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;2145916740&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0769230769231&quot;,&quot;title&quot;:&quot;&quot;,&quot;smoothgallery_link&quot;:&quot;&quot;}\" data-image-title=\"donald jamones\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-jamones.jpg?fit=480%2C360&amp;ssl=1\" class=\"aligncenter wp-image-6304\" title=\"donald jamones\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-jamones.jpg?resize=611%2C458&#038;ssl=1\" alt=\"\" width=\"611\" height=\"458\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-jamones.jpg?w=480&amp;ssl=1 480w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-jamones.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-jamones.jpg?resize=150%2C112&amp;ssl=1 150w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-jamones.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"auto, (max-width: 611px) 100vw, 611px\" \/>award-winning <a>Eiriz jamones<\/a><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21946\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-team\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-team.jpg?fit=500%2C374&amp;ssl=1\" data-orig-size=\"500,374\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1533391486&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0588235294118&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald team\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-team.jpg?fit=500%2C374&amp;ssl=1\" class=\"aligncenter wp-image-21946\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-team.jpg?resize=611%2C457&#038;ssl=1\" alt=\"\" width=\"611\" height=\"457\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-team.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-team.jpg?resize=300%2C224&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-team.jpg?resize=138%2C104&amp;ssl=1 138w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-team.jpg?resize=444%2C332&amp;ssl=1 444w\" sizes=\"auto, (max-width: 611px) 100vw, 611px\" \/>team Donald<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19461\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-mariano-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-mariano-2.jpg?fit=500%2C373&amp;ssl=1\" data-orig-size=\"500,373\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 6s&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1502114596&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.15&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald mariano (2)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-mariano-2.jpg?fit=500%2C373&amp;ssl=1\" class=\"aligncenter wp-image-19461\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-mariano-2.jpg?resize=597%2C445&#038;ssl=1\" alt=\"\" width=\"597\" height=\"445\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-mariano-2.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-mariano-2.jpg?resize=300%2C224&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-mariano-2.jpg?resize=138%2C104&amp;ssl=1 138w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-mariano-2.jpg?resize=444%2C331&amp;ssl=1 444w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/>owner Mariano Garc\u00eda<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"38556\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-8\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-8.jpg?fit=550%2C640&amp;ssl=1\" data-orig-size=\"550,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1770896967&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (8)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-8.jpg?fit=550%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-38556\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-8.jpg?resize=550%2C640&#038;ssl=1\" alt=\"\" width=\"550\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-8.jpg?w=550&amp;ssl=1 550w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-8.jpg?resize=258%2C300&amp;ssl=1 258w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-8.jpg?resize=382%2C444&amp;ssl=1 382w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/>\u00a0\u00a0Mariano with daughter Conchi<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"38557\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-26-9\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-9.jpg?fit=640%2C592&amp;ssl=1\" data-orig-size=\"640,592\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1770898804&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 26 (9)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-9.jpg?fit=640%2C592&amp;ssl=1\" class=\"aligncenter size-full wp-image-38557\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-9.jpg?resize=640%2C592&#038;ssl=1\" alt=\"\" width=\"640\" height=\"592\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-9.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-9.jpg?resize=300%2C278&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-9.jpg?resize=618%2C572&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-26-9.jpg?resize=444%2C411&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>the wall of awards (some of them!)<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"36113\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-25-3\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-3.jpg?fit=640%2C512&amp;ssl=1\" data-orig-size=\"640,512\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1740227807&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 25 (3)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-3.jpg?fit=640%2C512&amp;ssl=1\" class=\"aligncenter size-full wp-image-36113\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-3.jpg?resize=640%2C512&#038;ssl=1\" alt=\"\" width=\"640\" height=\"512\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-3.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-3.jpg?resize=300%2C240&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-3.jpg?resize=618%2C494&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-3.jpg?resize=444%2C355&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>upstairs dining room<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"36103\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-25-5\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-5.jpg?fit=640%2C484&amp;ssl=1\" data-orig-size=\"640,484\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1740227874&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 25 (5)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-5.jpg?fit=640%2C484&amp;ssl=1\" class=\"aligncenter size-full wp-image-36103\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-5.jpg?resize=640%2C484&#038;ssl=1\" alt=\"\" width=\"640\" height=\"484\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-5.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-5.jpg?resize=300%2C227&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-5.jpg?resize=618%2C467&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-5.jpg?resize=138%2C104&amp;ssl=1 138w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-5.jpg?resize=444%2C336&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"36114\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-25-4\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-4.jpg?fit=640%2C462&amp;ssl=1\" data-orig-size=\"640,462\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1740227825&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 25 (4)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-4.jpg?fit=640%2C462&amp;ssl=1\" class=\"aligncenter size-full wp-image-36114\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-4.jpg?resize=640%2C462&#038;ssl=1\" alt=\"\" width=\"640\" height=\"462\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-4.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-4.jpg?resize=300%2C217&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-4.jpg?resize=618%2C446&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-4.jpg?resize=444%2C321&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"36104\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-25-6\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-6.jpg?fit=479%2C640&amp;ssl=1\" data-orig-size=\"479,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1740227891&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 25 (6)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-6.jpg?fit=479%2C640&amp;ssl=1\" class=\"aligncenter size-full wp-image-36104\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-6.jpg?resize=479%2C640&#038;ssl=1\" alt=\"\" width=\"479\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-6.jpg?w=479&amp;ssl=1 479w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-6.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-6.jpg?resize=332%2C444&amp;ssl=1 332w\" sizes=\"auto, (max-width: 479px) 100vw, 479px\" \/><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"36106\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-25-8\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-8.jpg?fit=640%2C480&amp;ssl=1\" data-orig-size=\"640,480\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1740227973&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 25 (8)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-8.jpg?fit=640%2C480&amp;ssl=1\" class=\"aligncenter size-full wp-image-36106\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-8.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-8.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-8.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-8.jpg?resize=618%2C464&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-8.jpg?resize=138%2C104&amp;ssl=1 138w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-8.jpg?resize=444%2C333&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"37144\" data-permalink=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/donald-25-15\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-15.jpg?fit=640%2C480&amp;ssl=1\" data-orig-size=\"640,480\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;Picasa&quot;,&quot;camera&quot;:&quot;iPhone 15 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1755952475&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donald 25 (15)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-15.jpg?fit=640%2C480&amp;ssl=1\" class=\"aligncenter size-full wp-image-37144\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-15.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-15.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-15.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-15.jpg?resize=618%2C464&amp;ssl=1 618w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-15.jpg?resize=138%2C104&amp;ssl=1 138w, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2011\/10\/donald-25-15.jpg?resize=444%2C333&amp;ssl=1 444w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: center;\">~ <a href=\"https:\/\/azahar-sevilla.com\/sevilletapas\/cafeteria-donald\/\"><strong>back to top<\/strong><\/a> ~<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-780\" title=\"orange\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/wp-content\/uploads\/2009\/06\/orange.gif?resize=17%2C28\" alt=\"orange\" width=\"17\" height=\"28\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-780\" title=\"orange\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/wp-content\/uploads\/2009\/06\/orange.gif?resize=17%2C28\" alt=\"orange\" width=\"17\" height=\"28\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-780\" title=\"orange\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/wp-content\/uploads\/2009\/06\/orange.gif?resize=17%2C28\" alt=\"orange\" width=\"17\" height=\"28\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-780\" title=\"orange\" src=\"https:\/\/i0.wp.com\/azahar-sevilla.com\/wp-content\/uploads\/2009\/06\/orange.gif?resize=17%2C28\" alt=\"orange\" width=\"17\" height=\"28\" \/><br \/>\n<strong>Updated May 2026<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Updated May 2026 Cafeter\u00eda Donald has been going strong for 52 years and is a neighbourhood taurino-themed tapas bar and restaurant that serves up award-winning Eiriz jamones (also award-winning ensaladilla) along with fresh fish and seafood brought in daily from Huelva. It&#8217;s also my local, just a few minutes from my house. My favourite spot [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[254],"tags":[362,728,729,730],"class_list":["post-6312","post","type-post","status-publish","format-standard","hentry","category-cafeteria-donald","tag-cafeteria-donald-2","tag-sevilla","tag-spain","tag-tapas"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1sdVO-1DO","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":26933,"url":"https:\/\/azahar-sevilla.com\/sevilletapas\/bodega-la-hermandad\/","url_meta":{"origin":6312,"position":0},"title":"Bodega La Hermandad","author":"Shawn","date":"April 28, 2021","format":false,"excerpt":"Updated August 2025 When the bar next door to his well-known Cafeter\u00eda Donald became available in 2020, Mariano Garc\u00eda didn't hesitate. He immediately saw how well this location would work in tandem as a sister bar, especially with the ample sidewalk terrace and large windows that open onto the street.\u2026","rel":"","context":"In &quot;Bodega La Hermandad&quot;","block_context":{"text":"Bodega La Hermandad","link":"https:\/\/azahar-sevilla.com\/sevilletapas\/category\/bodega-la-hermandad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2021\/04\/bodega-h-25-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2021\/04\/bodega-h-25-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2021\/04\/bodega-h-25-3.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":37928,"url":"https:\/\/azahar-sevilla.com\/sevilletapas\/bar-rodriguez\/","url_meta":{"origin":6312,"position":1},"title":"Bar Rodr\u00edguez","author":"Shawn","date":"January 18, 2026","format":false,"excerpt":"Updated March 2026 Founded in 1988 by Miguel Rodr\u00edguez, and now run by his cousin Pedro D\u00edaz and friends Pedro Gallego, Bar Rodr\u00edguez is a true bar de barrio. I remember going there some 25 years ago, when I used to frequent the La Imperdible theatre. It recently came back\u2026","rel":"","context":"In &quot;Bar Rodr\u00edguez&quot;","block_context":{"text":"Bar Rodr\u00edguez","link":"https:\/\/azahar-sevilla.com\/sevilletapas\/category\/bar-rodriguez\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2026\/01\/b-rodriguez-15.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9367,"url":"https:\/\/azahar-sevilla.com\/sevilletapas\/blanca-paloma\/","url_meta":{"origin":6312,"position":2},"title":"Blanca Paloma","author":"Shawn","date":"October 23, 2012","format":false,"excerpt":"Updated December 2025 Yet another family-run bar taken over by a corporate group. A growing trend here. Very sorry to see Blanca Paloma go this route but I had some good times here so here I will leave this as a keepsake of those times, though obviously the review below\u2026","rel":"","context":"In &quot;Blanca Paloma&quot;","block_context":{"text":"Blanca Paloma","link":"https:\/\/azahar-sevilla.com\/sevilletapas\/category\/blanca-paloma\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2012\/10\/blanca-paloma-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2012\/10\/blanca-paloma-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2012\/10\/blanca-paloma-1.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":7390,"url":"https:\/\/azahar-sevilla.com\/sevilletapas\/el-cairo\/","url_meta":{"origin":6312,"position":3},"title":"El Cairo Restaurante","author":"Shawn","date":"March 18, 2012","format":false,"excerpt":"Updated March 2026 Founded in November 1977 by Juan Luis Salas and Manuela Ana Lozano, El Cairo opened as a small tapas bar occupying just 60 square metres of the building that the couple eventually purchased in 1983. In preparation for the upcoming Expo 93 they closed the building for\u2026","rel":"","context":"In &quot;El Cairo&quot;","block_context":{"text":"El Cairo","link":"https:\/\/azahar-sevilla.com\/sevilletapas\/category\/el-cairo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2012\/03\/cairo-25-12.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2012\/03\/cairo-25-12.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2012\/03\/cairo-25-12.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":16700,"url":"https:\/\/azahar-sevilla.com\/sevilletapas\/la-goleta-alvaro-peregil\/","url_meta":{"origin":6312,"position":4},"title":"Taberna La Goleta (Alvaro Peregil)","author":"Shawn","date":"March 5, 2016","format":false,"excerpt":"La Goleta (The Schooner) is a tiny bar in the Santa Cruz owned by Alvaro Peregil (son of the late flamenco singer Pepe Peregil). Originally founded as a wine store by Alvaro's grandfather in 1904 it still maintains its original features, such as the mahogany bar, making it stand out\u2026","rel":"","context":"In &quot;Taberna La Goleta (Alvaro Peregil)&quot;","block_context":{"text":"Taberna La Goleta (Alvaro Peregil)","link":"https:\/\/azahar-sevilla.com\/sevilletapas\/category\/la-goleta-alvaro-peregil\/"},"img":{"alt_text":"peregil (1)","src":"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2016\/02\/peregil-1.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":20081,"url":"https:\/\/azahar-sevilla.com\/sevilletapas\/restaurante-salas\/","url_meta":{"origin":6312,"position":5},"title":"Restaurante Salas","author":"Shawn","date":"November 10, 2017","format":false,"excerpt":"Updated December 2025 Another of my neighbourhood (El Arenal) favourites. Sister bar to El Cairo just around the corner, Salas has a very sevillano feel to it. Part of the reason for this is that's it's built on part of the frontage of the neo-Mudejar building next door, designed by\u2026","rel":"","context":"In &quot;Restaurante Salas&quot;","block_context":{"text":"Restaurante Salas","link":"https:\/\/azahar-sevilla.com\/sevilletapas\/category\/restaurante-salas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2017\/11\/salas-25-11.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2017\/11\/salas-25-11.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/azahar-sevilla.com\/sevilletapas\/wp-content\/uploads\/2017\/11\/salas-25-11.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/azahar-sevilla.com\/sevilletapas\/wp-json\/wp\/v2\/posts\/6312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azahar-sevilla.com\/sevilletapas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/azahar-sevilla.com\/sevilletapas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/azahar-sevilla.com\/sevilletapas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/azahar-sevilla.com\/sevilletapas\/wp-json\/wp\/v2\/comments?post=6312"}],"version-history":[{"count":76,"href":"https:\/\/azahar-sevilla.com\/sevilletapas\/wp-json\/wp\/v2\/posts\/6312\/revisions"}],"predecessor-version":[{"id":38578,"href":"https:\/\/azahar-sevilla.com\/sevilletapas\/wp-json\/wp\/v2\/posts\/6312\/revisions\/38578"}],"wp:attachment":[{"href":"https:\/\/azahar-sevilla.com\/sevilletapas\/wp-json\/wp\/v2\/media?parent=6312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/azahar-sevilla.com\/sevilletapas\/wp-json\/wp\/v2\/categories?post=6312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/azahar-sevilla.com\/sevilletapas\/wp-json\/wp\/v2\/tags?post=6312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}